{"id":7,"date":"2023-09-20T17:35:47","date_gmt":"2023-09-20T15:35:47","guid":{"rendered":"https:\/\/colegiosantaclaudiamelipilla.com\/?page_id=7"},"modified":"2026-03-05T21:07:46","modified_gmt":"2026-03-05T20:07:46","slug":"inicio","status":"publish","type":"page","link":"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/inicio\/","title":{"rendered":""},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><video class=\"wp-block-cover__video-background intrinsic-ignore\" autoplay muted loop playsinline src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/Banner-X-3.mp4\" data-object-fit=\"cover\"><\/video><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-ast-global-color-5-background-color has-background is-layout-constrained wp-container-core-group-is-layout-1 wp-block-group-is-layout-constrained\" style=\"padding-bottom:0px\">\n<div class=\"wp-block-columns are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-container-core-column-is-layout-1 wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/colegiosantaclaudiamelipilla.com\/\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/home.png\" alt=\"\" class=\"wp-image-99\" style=\"object-fit:cover;width:56px;height:56px\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/home.png 512w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/home-300x300.png 300w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/home-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-left\" style=\"margin-top:16px\"><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-container-core-column-is-layout-2 wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/documentacion-2\/\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/documentacion.png\" alt=\"\" class=\"wp-image-97\" style=\"width:56px;height:56px\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/documentacion.png 512w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/documentacion-300x300.png 300w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/documentacion-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-left\" style=\"margin-top:16px\"><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-container-core-column-is-layout-3 wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/galeria-de-fotos\/\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/galeria.png\" alt=\"\" class=\"wp-image-100\" style=\"object-fit:cover;width:56px;height:56px\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/galeria.png 512w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/galeria-300x300.png 300w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/galeria-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-left\" style=\"margin-top:16px\"><\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-container-core-column-is-layout-4 wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/contacto\/\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/contact-mail_3095583.png\" alt=\"\" class=\"wp-image-101\" style=\"object-fit:cover;width:56px;height:56px\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/contact-mail_3095583.png 512w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/contact-mail_3095583-300x300.png 300w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2023\/09\/contact-mail_3095583-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-left\" style=\"margin-top:16px\"><\/h3>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-container-core-group-is-layout-2 wp-block-group-is-layout-constrained\" id=\"services\" style=\"padding-top:144px;padding-bottom:0px\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"834\" height=\"1024\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2026\/02\/1000030211-834x1024.png\" alt=\"\" class=\"wp-image-1013\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2026\/02\/1000030211-834x1024.png 834w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2026\/02\/1000030211-244x300.png 244w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2026\/02\/1000030211-768x943.png 768w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2026\/02\/1000030211-1251x1536.png 1251w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2026\/02\/1000030211.png 1541w\" sizes=\"auto, (max-width: 834px) 100vw, 834px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2026\/03\/Red-and-White-Modern-No-Cell-Phone-Metal-Sign-768x1024.png\" alt=\"\" class=\"wp-image-1025\" style=\"width:542px;height:auto\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2026\/03\/Red-and-White-Modern-No-Cell-Phone-Metal-Sign-768x1024.png 768w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2026\/03\/Red-and-White-Modern-No-Cell-Phone-Metal-Sign-225x300.png 225w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2026\/03\/Red-and-White-Modern-No-Cell-Phone-Metal-Sign-1152x1536.png 1152w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2026\/03\/Red-and-White-Modern-No-Cell-Phone-Metal-Sign-1536x2048.png 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:108px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-4 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"732\" height=\"1024\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/05\/485938924_1068590718619712_8509096170435343416_n-732x1024.jpg\" alt=\"\" class=\"wp-image-900\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/05\/485938924_1068590718619712_8509096170435343416_n-732x1024.jpg 732w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/05\/485938924_1068590718619712_8509096170435343416_n-214x300.jpg 214w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/05\/485938924_1068590718619712_8509096170435343416_n-768x1075.jpg 768w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/05\/485938924_1068590718619712_8509096170435343416_n-1097x1536.jpg 1097w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/05\/485938924_1068590718619712_8509096170435343416_n.jpg 1463w\" sizes=\"auto, (max-width: 732px) 100vw, 732px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"841\" height=\"564\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/05\/76fcdb59b21882cd19cfeee645031e98.png\" alt=\"\" class=\"wp-image-902\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/05\/76fcdb59b21882cd19cfeee645031e98.png 841w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/05\/76fcdb59b21882cd19cfeee645031e98-300x201.png 300w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/05\/76fcdb59b21882cd19cfeee645031e98-768x515.png 768w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-5 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-6 wp-block-columns-is-layout-flex\" style=\"border-style:none;border-width:0px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.67%\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3459-1024x683.jpg\" alt=\"\" class=\"wp-image-358\" style=\"border-width:4px;border-radius:16px\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3459-1024x683.jpg 1024w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3459-300x200.jpg 300w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3459-768x512.jpg 768w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3459-1536x1024.jpg 1536w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3459-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large has-custom-border\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3466-683x1024.jpg\" alt=\"\" class=\"wp-image-365\" style=\"border-width:5px;border-radius:14px\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3466-683x1024.jpg 683w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3466-200x300.jpg 200w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3466-768x1152.jpg 768w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3466-1024x1536.jpg 1024w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3466-1365x2048.jpg 1365w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/04\/IMG_3466-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7 wp-block-columns-is-layout-flex\" style=\"margin-top:50px\">\n<div class=\"wp-block-column is-layout-flow wp-container-core-column-is-layout-15 wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-container-core-column-is-layout-16 wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-container-core-column-is-layout-17 wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-cover alignwide is-light has-small-font-size wp-duotone-unset-1\" style=\"border-style:none;border-width:0px;border-radius:22px;margin-top:0;margin-bottom:0;padding-top:0em;padding-right:0em;padding-bottom:0em;padding-left:0em;min-height:666px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><video class=\"wp-block-cover__video-background intrinsic-ignore\" autoplay muted loop playsinline src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/Diseno-sin-titulo.mp4\" data-object-fit=\"cover\"><\/video><div class=\"wp-block-cover__inner-container is-layout-flow wp-container-core-cover-is-layout-2 wp-block-cover-is-layout-flow\">\n<p><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-container-core-group-is-layout-4 wp-block-group-is-layout-constrained\" id=\"whyus\" style=\"padding-top:144px;padding-bottom:144px\">\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9 wp-block-columns-is-layout-flex\" style=\"margin-top:60px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-cover alignwide has-small-font-size wp-duotone-unset-2\" style=\"border-style:none;border-width:0px;border-radius:22px;margin-top:0;margin-bottom:0;padding-top:0em;padding-right:0em;padding-bottom:0em;padding-left:0em;min-height:666px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#0c092a\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" class=\"wp-block-cover__image-background wp-image-824\" alt=\"\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/11\/Copia-de-Azul-oscuro-cian-tecnologia-moderna-noticias-generales-logotipo.gif\" data-object-fit=\"cover\"\/><div class=\"wp-block-cover__inner-container is-layout-flow wp-container-core-cover-is-layout-3 wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:71px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-10 wp-block-columns-is-layout-flex\" style=\"margin-bottom:0\">\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-3a306cc9c7239079e4a1f363c4ddf675 is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#ffe97d;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>CONTACTO<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center\"><strong><strong>CLICK EN LA IMAGEN<\/strong><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-css-opacity has-background is-style-wide\" style=\"background-color:#000000;color:#000000\"\/>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-thumbnail\"><a href=\"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/contacto\/\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/Lovepik_com-450157744-New-Contact-150x150.png\" alt=\"\" class=\"wp-image-451\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/Lovepik_com-450157744-New-Contact-150x150.png 150w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/Lovepik_com-450157744-New-Contact-300x300.png 300w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/Lovepik_com-450157744-New-Contact-1024x1024.png 1024w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/Lovepik_com-450157744-New-Contact-768x768.png 768w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/Lovepik_com-450157744-New-Contact-1536x1536.png 1536w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/Lovepik_com-450157744-New-Contact-2048x2048.png 2048w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-buttons alignfull is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-5171d0bad3a5513a24807c643256dffd is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#d1d1e1;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>LISTAS DE UTILES A\u00d1O 2026<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center\"><strong>CLICK EN LA IMAGEN<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-thumbnail\"><a href=\"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/listas-de-utiles-2024\/\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/02\/pngegg-150x150.png\" alt=\"\" class=\"wp-image-215\"\/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-buttons alignfull is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-2 wp-block-buttons-is-layout-flex\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-text-color has-background has-link-color wp-elements-ba50893d2d426a8cbba51f8e8b28c97e is-layout-flow wp-block-column-is-layout-flow\" style=\"color:#000000;background-color:#c0ebf1;padding-top:2em;padding-right:2em;padding-bottom:2em;padding-left:2em\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>GALERIA DE FOTOS<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-center\"><strong><strong>CLICK EN LA IMAGEN<\/strong><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-thumbnail\"><a href=\"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/galeria-de-fotos\/\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/photo-gallery-150x150.png\" alt=\"\" class=\"wp-image-453\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/photo-gallery-150x150.png 150w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/photo-gallery-300x300.png 300w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/05\/photo-gallery.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-buttons alignfull is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3 wp-block-buttons-is-layout-flex\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-ast-global-color-4-background-color has-background is-layout-constrained wp-container-core-group-is-layout-3 wp-block-group-is-layout-constrained\" id=\"reviews\">\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<div style=\"height:33px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-11 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/03\/maxresdefault-1024x576.jpg\" alt=\"\" class=\"wp-image-865\" style=\"width:651px;height:auto\" srcset=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/03\/maxresdefault-1024x576.jpg 1024w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/03\/maxresdefault-300x169.jpg 300w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/03\/maxresdefault-768x432.jpg 768w, https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2025\/03\/maxresdefault.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00bfC\u00f3mo evitar el ciberbullying? | UC CHRISTUS\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/DzGm8vr1BNk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\" style=\"margin-top:0;margin-bottom:0\"\/>\n\n\n\n<div style=\"height:61px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-cover has-small-font-size wp-duotone-unset-3\" style=\"border-style:none;border-width:0px;border-radius:22px;margin-top:0;margin-bottom:0;padding-top:0em;padding-right:0em;padding-bottom:0em;padding-left:0em;min-height:666px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><video class=\"wp-block-cover__video-background intrinsic-ignore\" autoplay muted loop playsinline src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/06\/centro-estudiantil.mp4\" data-object-fit=\"cover\"><\/video><div class=\"wp-block-cover__inner-container is-layout-flow wp-container-core-cover-is-layout-4 wp-block-cover-is-layout-flow\">\n<p><\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\" style=\"margin-top:0;margin-bottom:0\"\/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-12 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-13 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover aligncenter is-light has-small-font-size wp-duotone-unset-4\" style=\"border-style:none;border-width:0px;border-radius:22px;margin-top:0;margin-bottom:0;padding-top:0em;padding-right:0em;padding-bottom:0em;padding-left:0em;min-height:666px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><video class=\"wp-block-cover__video-background intrinsic-ignore\" autoplay muted loop playsinline src=\"https:\/\/colegiosantaclaudiamelipilla.com\/wp-content\/uploads\/2024\/06\/Colorful-Blue-and-Purple-Animated-YouTube-Outro.mp4\" data-object-fit=\"cover\"><\/video><div class=\"wp-block-cover__inner-container is-layout-flow wp-container-core-cover-is-layout-5 wp-block-cover-is-layout-flow\">\n<p><\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CONTACTO CLICK EN LA IMAGEN LISTAS DE UTILES A\u00d1O 2026 CLICK EN LA IMAGEN GALERIA DE FOTOS CLICK EN LA IMAGEN<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/wp-json\/wp\/v2\/pages\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":157,"href":"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/wp-json\/wp\/v2\/pages\/7\/revisions"}],"predecessor-version":[{"id":1028,"href":"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/wp-json\/wp\/v2\/pages\/7\/revisions\/1028"}],"wp:attachment":[{"href":"https:\/\/colegiosantaclaudiamelipilla.com\/index.php\/wp-json\/wp\/v2\/media?parent=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}